{"id":2144,"date":"2023-07-25T12:37:26","date_gmt":"2023-07-25T10:37:26","guid":{"rendered":"https:\/\/elektroelement.com.mk\/?page_id=2144"},"modified":"2023-07-31T10:00:02","modified_gmt":"2023-07-31T08:00:02","slug":"ponuda","status":"publish","type":"page","link":"https:\/\/elektroelement.com.mk\/en\/ponuda\/","title":{"rendered":"\u041f\u043e\u043d\u0443\u0434\u0430"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1690790398419\">\n\t\t\t\t<div   class=\"jws-vc-row-ovelay\"><\/div>\n                <div  class=\"jws-over-lay\"><\/div>\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  vc_custom_1690536056603\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"500\" src=\"https:\/\/elektroelement.com.mk\/wp-content\/uploads\/2023\/07\/eesPonudaBanner.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"eesPonudaBanner\" srcset=\"https:\/\/elektroelement.com.mk\/wp-content\/uploads\/2023\/07\/eesPonudaBanner.jpg 1600w, https:\/\/elektroelement.com.mk\/wp-content\/uploads\/2023\/07\/eesPonudaBanner-300x94.jpg 300w, https:\/\/elektroelement.com.mk\/wp-content\/uploads\/2023\/07\/eesPonudaBanner-1024x320.jpg 1024w, https:\/\/elektroelement.com.mk\/wp-content\/uploads\/2023\/07\/eesPonudaBanner-768x240.jpg 768w, https:\/\/elektroelement.com.mk\/wp-content\/uploads\/2023\/07\/eesPonudaBanner-1536x480.jpg 1536w, https:\/\/elektroelement.com.mk\/wp-content\/uploads\/2023\/07\/eesPonudaBanner-18x6.jpg 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t<div   class=\"jws-vc-row-ovelay\"><\/div>\n                <div  class=\"jws-over-lay\"><\/div>\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_sep_color_grey vc_separator-has-text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><div class=\"vc_icon_element vc_icon_element-outer vc_icon_element-align-left\"><div class=\"vc_icon_element-inner vc_icon_element-color-blue vc_icon_element-size-md vc_icon_element-style- vc_icon_element-background-color-grey\" ><span class=\"vc_icon_element-icon far fa-envelope\" ><\/span><\/div><\/div><h4>\u041f\u043e\u0431\u0430\u0440\u0430\u0458 \u043f\u043e\u043d\u0443\u0434\u0430 \/ \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430<\/h4><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t<div   class=\"jws-vc-row-ovelay\"><\/div>\n                <div  class=\"jws-over-lay\"><\/div>\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2143-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"2143\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2144#wpcf7-f2143-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/2144#wpcf7-f2143-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2143\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2143-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form_contact\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u0418\u043c\u0435\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u0415-\u043f\u043e\u0448\u0442\u0430\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-524\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u0422\u0435\u043b\u0435\u0444\u043e\u043d\" value=\"\" type=\"tel\" name=\"tel-524\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"\u041f\u043e\u0440\u0430\u043a\u0430\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"\u0418\u0441\u043f\u0440\u0430\u0442\u0438\" \/>\n\t<\/p>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"144\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"\u041f\u043e\u0431\u0430\u0440\u0430\u0458 \u043f\u043e\u043d\u0443\u0434\u0430 \/ \u0441\u043e\u0440\u0430\u0431\u043e\u0442\u043a\u0430 &#916;","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2144","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/elektroelement.com.mk\/en\/wp-json\/wp\/v2\/pages\/2144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elektroelement.com.mk\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elektroelement.com.mk\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elektroelement.com.mk\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elektroelement.com.mk\/en\/wp-json\/wp\/v2\/comments?post=2144"}],"version-history":[{"count":0,"href":"https:\/\/elektroelement.com.mk\/en\/wp-json\/wp\/v2\/pages\/2144\/revisions"}],"wp:attachment":[{"href":"https:\/\/elektroelement.com.mk\/en\/wp-json\/wp\/v2\/media?parent=2144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}